{"id":145,"count":1,"description":"","link":"https:\/\/www.indicasaude.com.br\/leads\/tag\/dicas-para-corretor-de-saude\/","name":"dicas para corretor de sa\u00fade","slug":"dicas-para-corretor-de-saude","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.indicasaude.com.br\/leads\/wp-json\/wp\/v2\/tags\/145"}],"collection":[{"href":"https:\/\/www.indicasaude.com.br\/leads\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.indicasaude.com.br\/leads\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.indicasaude.com.br\/leads\/wp-json\/wp\/v2\/posts?tags=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}